{"id":2476,"date":"2024-11-07T16:13:07","date_gmt":"2024-11-07T21:13:07","guid":{"rendered":"https:\/\/lecam.ca\/campingmelbourne\/restaurants\/"},"modified":"2024-11-11T10:30:35","modified_gmt":"2024-11-11T15:30:35","slug":"restaurants","status":"publish","type":"page","link":"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/","title":{"rendered":"Restaurants"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2476\" class=\"elementor elementor-2476 elementor-2221\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd593ba e-flex e-con-boxed e-con e-parent\" data-id=\"fd593ba\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2f9ae8f e-con-full e-flex e-con e-child\" data-id=\"2f9ae8f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-00a505a elementor-widget elementor-widget-heading\" data-id=\"00a505a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Restaurants<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c6d991 e-flex e-con-boxed e-con e-parent\" data-id=\"8c6d991\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fed4370 e-con-full e-flex e-con e-child\" data-id=\"fed4370\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26fbd74 uael-post__link-complete-yes uael-equal__height-yes elementor-widget elementor-widget-uael-posts\" data-id=\"26fbd74\" data-element_type=\"widget\" data-settings=\"{&quot;classic_slides_to_show&quot;:3,&quot;classic_slides_to_show_tablet&quot;:2,&quot;classic_slides_to_show_mobile&quot;:1,&quot;classic_pagination_type&quot;:&quot;ajax&quot;}\" data-widget_type=\"uael-posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-post__header\">\n\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__body\">\n\t\t\t\n\t\t\n\t\t<div class=\"uael-blog-terms-position- uael-post-image-top uael-post-grid uael-posts\" data-query-type=\"custom\" data-structure=\"normal\" data-layout=\"\" data-page=\"2476\" data-skin=\"classic\" data-filter-default=\"\" data-offset-top=\"30\" >\n\n\t\t\t\t\t\t\t<div class=\"uael-post-grid__inner uael-post__columns-3 uael-post__columns-tablet-2 uael-post__columns-mobile-1\">\n\t\t\t\n<div class=\"uael-post-wrapper   restaurants things-to-do \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/la-boucane-bbq\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/la-boucane-bbq\/\" target=\"_self\" title=\"La Boucane BBQ\"><img fetchpriority=\"high\" decoding=\"async\" width=\"599\" height=\"400\" src=\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/la-boucane.jpg\" class=\"attachment-full size-full wp-image-2050\" alt=\"LaBoucane BBQ\" srcset=\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/la-boucane.jpg 599w, https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/la-boucane-300x200.jpg 300w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/la-boucane-bbq\/\" target=\"_self\">\n\t\t\t\tLa Boucane BBQ\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/campingmelbourne.com\/en\/la-boucane-bbq\/\" target=\"_self\" aria-labelledby=\"uael-post-2346\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-2346>Learn More \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   restaurants things-to-do \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/restaurant-de-la-gare\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/restaurant-de-la-gare\/\" target=\"_self\" title=\"Restaurant de la gare\"><img decoding=\"async\" width=\"1025\" height=\"685\" src=\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre.jpg\" class=\"attachment-full size-full wp-image-2057\" alt=\"Restaurant de la gare\" srcset=\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre.jpg 1025w, https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre-300x200.jpg 300w, https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre-768x513.jpg 768w\" sizes=\"(max-width: 1025px) 100vw, 1025px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/restaurant-de-la-gare\/\" target=\"_self\">\n\t\t\t\tRestaurant de la gare\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/campingmelbourne.com\/en\/restaurant-de-la-gare\/\" target=\"_self\" aria-labelledby=\"uael-post-2353\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-2353>Learn More \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   restaurants things-to-do \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/la-desserte-restaurant\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/la-desserte-restaurant\/\" target=\"_self\" title=\"La Desserte Restaurant\"><img decoding=\"async\" width=\"1025\" height=\"685\" src=\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/restaurant-la-desserte.jpg\" class=\"attachment-full size-full wp-image-2043\" alt=\"Restaurant La Desserte\" srcset=\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/restaurant-la-desserte.jpg 1025w, https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/restaurant-la-desserte-300x200.jpg 300w, https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/restaurant-la-desserte-768x513.jpg 768w\" sizes=\"(max-width: 1025px) 100vw, 1025px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/la-desserte-restaurant\/\" target=\"_self\">\n\t\t\t\tLa Desserte Restaurant\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/campingmelbourne.com\/en\/la-desserte-restaurant\/\" target=\"_self\" aria-labelledby=\"uael-post-2325\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-2325>Learn More \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   restaurants things-to-do \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/pizza-richmond\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/pizza-richmond\/\" target=\"_self\" title=\"Pizza Richmond\"><img loading=\"lazy\" decoding=\"async\" width=\"1025\" height=\"685\" src=\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/richmond-pizza.jpg\" class=\"attachment-full size-full wp-image-2010\" alt=\"Pizza Richmond\" srcset=\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/richmond-pizza.jpg 1025w, https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/richmond-pizza-300x200.jpg 300w, https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/richmond-pizza-768x513.jpg 768w\" sizes=\"(max-width: 1025px) 100vw, 1025px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/pizza-richmond\/\" target=\"_self\">\n\t\t\t\tPizza Richmond\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/campingmelbourne.com\/en\/pizza-richmond\/\" target=\"_self\" aria-labelledby=\"uael-post-2314\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-2314>Learn More \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   restaurants things-to-do \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/restaurant-la-belle-view\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/restaurant-la-belle-view\/\" target=\"_self\" title=\"Restaurant La Belle View\"><img loading=\"lazy\" decoding=\"async\" width=\"1025\" height=\"685\" src=\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/golf-richmond-2.jpg\" class=\"attachment-full size-full wp-image-1516\" alt=\"golf richmond\" srcset=\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/golf-richmond-2.jpg 1025w, https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/golf-richmond-2-300x200.jpg 300w, https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/golf-richmond-2-768x513.jpg 768w\" sizes=\"(max-width: 1025px) 100vw, 1025px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/campingmelbourne.com\/en\/restaurant-la-belle-view\/\" target=\"_self\">\n\t\t\t\tRestaurant La Belle View\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/campingmelbourne.com\/en\/restaurant-la-belle-view\/\" target=\"_self\" aria-labelledby=\"uael-post-2309\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-2309>Learn More \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__footer\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-02c344c e-con-full e-flex e-con e-child\" data-id=\"02c344c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2bc8e6b elementor-widget elementor-widget-heading\" data-id=\"2bc8e6b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Categories<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adfeb70 hfe-nav-menu__breakpoint-none hfe-nav-menu__align-left hfe-submenu-icon-arrow hfe-link-redirect-child elementor-widget elementor-widget-navigation-menu\" data-id=\"adfeb70\" data-element_type=\"widget\" data-settings=\"{&quot;menu_space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;menu_space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-vertical hfe-nav-menu-layout vertical\" data-layout=\"vertical\">\n\t\t\t\t<div role=\"button\" class=\"hfe-nav-menu__toggle elementor-clickable\">\n\t\t\t\t\t<span class=\"screen-reader-text\">Menu<\/span>\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-vertical hfe-nav-menu__submenu-arrow\" data-toggle-icon=\"\" data-close-icon=\"\" data-full-width=\"\">\n\t\t\t\t\t<ul id=\"menu-1-adfeb70\" class=\"hfe-nav-menu\"><li id=\"menu-item-2266\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/campingmelbourne.com\/en\/attractions\/culture\/\" class = \"hfe-menu-item\">Culture<\/a><\/li>\n<li id=\"menu-item-3843\" class=\"menu-item menu-item-type-taxonomy menu-item-object-category parent hfe-creative-menu\"><a href=\"https:\/\/campingmelbourne.com\/en\/category\/family-games-en\/\" class = \"hfe-menu-item\">Family games<\/a><\/li>\n<li id=\"menu-item-2490\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/campingmelbourne.com\/en\/attractions\/food-industrie\/\" class = \"hfe-menu-item\">Food industrie<\/a><\/li>\n<li id=\"menu-item-2489\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/campingmelbourne.com\/en\/attractions\/museums\/\" class = \"hfe-menu-item\">Museums<\/a><\/li>\n<li id=\"menu-item-2488\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/\" class = \"hfe-menu-item\">Restaurants<\/a><\/li>\n<li id=\"menu-item-2491\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/campingmelbourne.com\/en\/attractions\/sports\/\" class = \"hfe-menu-item\">Sports<\/a><\/li>\n<\/ul> \n\t\t\t\t<\/nav>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Restaurants Restaurant de la gare Learn More \u2192 Restaurant La Belle View Learn More \u2192 La Desserte Restaurant Learn More \u2192 Pizza Richmond Learn More \u2192 Categories Menu Culture<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3600,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"disabled","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2476","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Restaurants - Camping Melbourne Estrie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurants - Camping Melbourne Estrie\" \/>\n<meta property=\"og:description\" content=\"Restaurants Restaurant de la gare Learn More \u2192 Restaurant La Belle View Learn More \u2192 La Desserte Restaurant Learn More \u2192 Pizza Richmond Learn More \u2192 Categories Menu Culture\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/\" \/>\n<meta property=\"og:site_name\" content=\"Camping Melbourne Estrie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/campingmelbournerichmond\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-11T15:30:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/\",\"url\":\"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/\",\"name\":\"Restaurants - Camping Melbourne Estrie\",\"isPartOf\":{\"@id\":\"https:\/\/campingmelbourne.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre.jpg\",\"datePublished\":\"2024-11-07T21:13:07+00:00\",\"dateModified\":\"2024-11-11T15:30:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/#primaryimage\",\"url\":\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre.jpg\",\"contentUrl\":\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/campingmelbourne.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attractions\",\"item\":\"https:\/\/campingmelbourne.com\/en\/attractions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Restaurants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/campingmelbourne.com\/en\/#website\",\"url\":\"https:\/\/campingmelbourne.com\/en\/\",\"name\":\"Camping Melbourne Estrie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/campingmelbourne.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/campingmelbourne.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/campingmelbourne.com\/en\/#organization\",\"name\":\"Camping Melbourne Estrie\",\"url\":\"https:\/\/campingmelbourne.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/campingmelbourne.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/logo-camping-melbourne-estrie.png\",\"contentUrl\":\"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/logo-camping-melbourne-estrie.png\",\"width\":125,\"height\":125,\"caption\":\"Camping Melbourne Estrie\"},\"image\":{\"@id\":\"https:\/\/campingmelbourne.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/campingmelbournerichmond\",\"https:\/\/www.youtube.com\/channel\/UCjiBSMgJii6aoZ7DJimO-9Q\",\"https:\/\/www.instagram.com\/campingmelbourneestrie\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurants - Camping Melbourne Estrie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/","og_locale":"en_US","og_type":"article","og_title":"Restaurants - Camping Melbourne Estrie","og_description":"Restaurants Restaurant de la gare Learn More \u2192 Restaurant La Belle View Learn More \u2192 La Desserte Restaurant Learn More \u2192 Pizza Richmond Learn More \u2192 Categories Menu Culture","og_url":"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/","og_site_name":"Camping Melbourne Estrie","article_publisher":"https:\/\/www.facebook.com\/campingmelbournerichmond","article_modified_time":"2024-11-11T15:30:35+00:00","og_image":[{"url":"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/","url":"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/","name":"Restaurants - Camping Melbourne Estrie","isPartOf":{"@id":"https:\/\/campingmelbourne.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/#primaryimage"},"image":{"@id":"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/#primaryimage"},"thumbnailUrl":"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre.jpg","datePublished":"2024-11-07T21:13:07+00:00","dateModified":"2024-11-11T15:30:35+00:00","breadcrumb":{"@id":"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/#primaryimage","url":"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre.jpg","contentUrl":"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/resto-de-la-garre.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/campingmelbourne.com\/en\/attractions\/restaurants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/campingmelbourne.com\/en\/"},{"@type":"ListItem","position":2,"name":"Attractions","item":"https:\/\/campingmelbourne.com\/en\/attractions\/"},{"@type":"ListItem","position":3,"name":"Restaurants"}]},{"@type":"WebSite","@id":"https:\/\/campingmelbourne.com\/en\/#website","url":"https:\/\/campingmelbourne.com\/en\/","name":"Camping Melbourne Estrie","description":"","publisher":{"@id":"https:\/\/campingmelbourne.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campingmelbourne.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/campingmelbourne.com\/en\/#organization","name":"Camping Melbourne Estrie","url":"https:\/\/campingmelbourne.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/campingmelbourne.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/logo-camping-melbourne-estrie.png","contentUrl":"https:\/\/campingmelbourne.com\/wp-content\/uploads\/2024\/11\/logo-camping-melbourne-estrie.png","width":125,"height":125,"caption":"Camping Melbourne Estrie"},"image":{"@id":"https:\/\/campingmelbourne.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/campingmelbournerichmond","https:\/\/www.youtube.com\/channel\/UCjiBSMgJii6aoZ7DJimO-9Q","https:\/\/www.instagram.com\/campingmelbourneestrie\/"]}]}},"_links":{"self":[{"href":"https:\/\/campingmelbourne.com\/en\/wp-json\/wp\/v2\/pages\/2476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campingmelbourne.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/campingmelbourne.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/campingmelbourne.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/campingmelbourne.com\/en\/wp-json\/wp\/v2\/comments?post=2476"}],"version-history":[{"count":0,"href":"https:\/\/campingmelbourne.com\/en\/wp-json\/wp\/v2\/pages\/2476\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/campingmelbourne.com\/en\/wp-json\/wp\/v2\/pages\/3600"}],"wp:attachment":[{"href":"https:\/\/campingmelbourne.com\/en\/wp-json\/wp\/v2\/media?parent=2476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}